{"id":64102,"date":"2024-09-24T13:37:46","date_gmt":"2024-09-24T13:37:46","guid":{"rendered":"https:\/\/ahmedbahaa.me\/?page_id=64102"},"modified":"2025-01-02T18:10:02","modified_gmt":"2025-01-02T18:10:02","slug":"our-program","status":"publish","type":"page","link":"https:\/\/ahmedbahaa.me\/en\/our-program\/","title":{"rendered":"Our Program"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"64102\" class=\"elementor elementor-64102\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8569ae6 elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"8569ae6\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d3a2214 sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"d3a2214\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3190c0c sc_height_huge sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"3190c0c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2367998 sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"2367998\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-77a0acf scheme_default elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"77a0acf\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1464e68 sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"1464e68\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-22b3148 sc_fly_static elementor-widget elementor-widget-trx_sc_title\" data-id=\"22b3148\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"trx_sc_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div\t\tclass=\"sc_title sc_title_default\" ><span class=\"sc_item_subtitle sc_title_subtitle sc_item_subtitle_above sc_item_title_style_default\">main issues<\/span><h1 class=\"sc_item_title sc_title_title sc_item_title_style_default sc_item_title_tag\"\n\t\t\t><span class=\"sc_item_title_text\">Our priorities<\/span><\/h1><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-e09d3ba sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"e09d3ba\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bfdd54f sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"bfdd54f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-174ee3e sc_fly_static elementor-widget elementor-widget-text-editor\" data-id=\"174ee3e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tSed ut perspiciatis unde omnis iste natus ut perspic iatis unde omnis iste perspiciatis ut perspiciatis unde omnis iste natus.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-827cc1b sc_layouts_column_align_right sc_layouts_column sc-mobile_layouts_column_align_left sc_layouts_column sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"827cc1b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-52219b8 sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"52219b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d4a5eea sc_fly_static elementor-widget elementor-widget-trx_sc_button\" data-id=\"d4a5eea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"trx_sc_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div\tclass=\"sc_item_button sc_button_wrap\" ><a href=\"https:\/\/ahmedbahaa.me\/en\/join-us\/\" class=\"sc_button sc_button_simple sc_button_size_small sc_button_icon_left color_style_dark\" ><span class=\"sc_button_text\"><span class=\"sc_button_title\">Join Us<\/span><\/span><\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-709001b7 scheme_light elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"709001b7\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-254454c sc_extra_bg_extra_left sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"254454c\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2ec0cf77 sc_height_small sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"2ec0cf77\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-690ef11a sc_fly_static elementor-widget elementor-widget-trx_sc_services\" data-id=\"690ef11a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"trx_sc_services.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"sc_services sc_services_strong sc_services_featured_top\"><div  class=\"sc_services_slider sc_item_slider slider_swiper_outer slider_outer slider_outer_nocontrols slider_outer_nopagination slider_outer_nocentered slider_outer_overflow_visible slider_outer_multi\">\n\t<div  data-slides-per-view-breakpoints=\"{&quot;999999&quot;:3}\" data-slides-space-breakpoints=\"{&quot;999999&quot;:30}\" class=\"slider_container swiper-slider-container slider_swiper slider_noresize slider_nocontrols slider_nopagination slider_nocentered slider_overflow_visible slider_multi\" data-slides-per-view=\"3\" data-slides-space=\"30\" data-effect=\"slide\" data-slides-min-width=\"200\" data-pagination=\"bullets\" data-direction=\"horizontal\" data-mouse-wheel=\"0\" data-autoplay=\"1\" data-loop=\"1\" data-free-mode=\"0\" data-slides-centered=\"0\" data-slides-overflow=\"1\">\n\t\t<div class=\"slides slider-wrapper swiper-wrapper sc_item_columns_3\"><div class=\"slider-slide swiper-slide\"><div data-post-id=\"68039\" class=\"sc_services_item sc_item_container post_container with_content with_image with_number post-68039 cpt_services type-cpt_services status-publish has-post-thumbnail hentry cpt_services_group-city\">\n\t\t<div class=\"sc_services_item_content\" style=\"background-image: url(https:\/\/ahmedbahaa.me\/wp-content\/uploads\/2024\/07\/service-image5-copyright-840x560.jpg);\">\n\t\t\t\t<div class=\"sc_services_item_content_inner\"><div class=\"sc_services_item_content_inner_top\"><span class=\"sc_services_item_number\">01.<\/span><\/div><div class=\"sc_services_item_content_inner_bottom\">\n                <h6 class=\"sc_services_item_title\"><a href=\"https:\/\/ahmedbahaa.me\/en\/services\/comfort-living\/\">Comfort living<\/a><\/h6>\n                <div class=\"sc_services_item_text\"><p>Sed ut perspiciatis unde omnis iste natus error sit voluptatem.<\/p>\n<\/div><\/div><\/div><a class=\"sc_services_item_link\" href=\"https:\/\/ahmedbahaa.me\/en\/services\/comfort-living\/\"><\/a><\/div><\/div><\/div><div class=\"slider-slide swiper-slide\"><div data-post-id=\"68040\" class=\"sc_services_item sc_item_container post_container with_content with_image with_number post-68040 cpt_services type-cpt_services status-publish has-post-thumbnail hentry cpt_services_group-city\">\n\t\t<div class=\"sc_services_item_content\" style=\"background-image: url(https:\/\/ahmedbahaa.me\/wp-content\/uploads\/2024\/07\/service-image6-copyright-840x1120.jpg);\">\n\t\t\t\t<div class=\"sc_services_item_content_inner\"><div class=\"sc_services_item_content_inner_top\"><span class=\"sc_services_item_number\">02.<\/span><\/div><div class=\"sc_services_item_content_inner_bottom\">\n                <h6 class=\"sc_services_item_title\"><a href=\"https:\/\/ahmedbahaa.me\/en\/services\/renewable-energy\/\">Renewable energy<\/a><\/h6>\n                <div class=\"sc_services_item_text\"><p>Sed ut perspiciatis unde omnis iste natus error sit voluptatem.<\/p>\n<\/div><\/div><\/div><a class=\"sc_services_item_link\" href=\"https:\/\/ahmedbahaa.me\/en\/services\/renewable-energy\/\"><\/a><\/div><\/div><\/div><div class=\"slider-slide swiper-slide\"><div data-post-id=\"68041\" class=\"sc_services_item sc_item_container post_container with_content with_image with_number post-68041 cpt_services type-cpt_services status-publish has-post-thumbnail hentry cpt_services_group-city\">\n\t\t<div class=\"sc_services_item_content\" style=\"background-image: url(https:\/\/ahmedbahaa.me\/wp-content\/uploads\/2024\/07\/service-image7-copyright-840x560.jpg);\">\n\t\t\t\t<div class=\"sc_services_item_content_inner\"><div class=\"sc_services_item_content_inner_top\"><span class=\"sc_services_item_number\">03.<\/span><\/div><div class=\"sc_services_item_content_inner_bottom\">\n                <h6 class=\"sc_services_item_title\"><a href=\"https:\/\/ahmedbahaa.me\/en\/services\/public-transport\/\">Public transport<\/a><\/h6>\n                <div class=\"sc_services_item_text\"><p>Sed ut perspiciatis unde omnis iste natus error sit voluptatem.<\/p>\n<\/div><\/div><\/div><a class=\"sc_services_item_link\" href=\"https:\/\/ahmedbahaa.me\/en\/services\/public-transport\/\"><\/a><\/div><\/div><\/div><div class=\"slider-slide swiper-slide\"><div data-post-id=\"68042\" class=\"sc_services_item sc_item_container post_container with_content with_image with_number post-68042 cpt_services type-cpt_services status-publish has-post-thumbnail hentry cpt_services_group-city\">\n\t\t<div class=\"sc_services_item_content\" style=\"background-image: url(https:\/\/ahmedbahaa.me\/wp-content\/uploads\/2024\/07\/service-image8-copyright-840x560.jpg);\">\n\t\t\t\t<div class=\"sc_services_item_content_inner\"><div class=\"sc_services_item_content_inner_top\"><span class=\"sc_services_item_number\">04.<\/span><\/div><div class=\"sc_services_item_content_inner_bottom\">\n                <h6 class=\"sc_services_item_title\"><a href=\"https:\/\/ahmedbahaa.me\/en\/services\/activities-for-kids\/\">Activities for kids<\/a><\/h6>\n                <div class=\"sc_services_item_text\"><p>Sed ut perspiciatis unde omnis iste natus error sit voluptatem.<\/p>\n<\/div><\/div><\/div><a class=\"sc_services_item_link\" href=\"https:\/\/ahmedbahaa.me\/en\/services\/activities-for-kids\/\"><\/a><\/div><\/div><\/div><div class=\"slider-slide swiper-slide\"><div data-post-id=\"68043\" class=\"sc_services_item sc_item_container post_container with_content with_image with_number post-68043 cpt_services type-cpt_services status-publish has-post-thumbnail hentry cpt_services_group-city\">\n\t\t<div class=\"sc_services_item_content\" style=\"background-image: url(https:\/\/ahmedbahaa.me\/wp-content\/uploads\/2024\/06\/service-image9-copyright-840x1008.jpg);\">\n\t\t\t\t<div class=\"sc_services_item_content_inner\"><div class=\"sc_services_item_content_inner_top\"><span class=\"sc_services_item_number\">05.<\/span><\/div><div class=\"sc_services_item_content_inner_bottom\">\n                <h6 class=\"sc_services_item_title\"><a href=\"https:\/\/ahmedbahaa.me\/en\/services\/sport-events\/\">Sport events<\/a><\/h6>\n                <div class=\"sc_services_item_text\"><p>Sed ut perspiciatis unde omnis iste natus error sit voluptatem.<\/p>\n<\/div><\/div><\/div><a class=\"sc_services_item_link\" href=\"https:\/\/ahmedbahaa.me\/en\/services\/sport-events\/\"><\/a><\/div><\/div><\/div><div class=\"slider-slide swiper-slide\"><div data-post-id=\"68044\" class=\"sc_services_item sc_item_container post_container with_content with_image with_number post-68044 cpt_services type-cpt_services status-publish has-post-thumbnail hentry cpt_services_group-city\">\n\t\t<div class=\"sc_services_item_content\" style=\"background-image: url(https:\/\/ahmedbahaa.me\/wp-content\/uploads\/2024\/06\/service-image10-copyright-840x560.jpg);\">\n\t\t\t\t<div class=\"sc_services_item_content_inner\"><div class=\"sc_services_item_content_inner_top\"><span class=\"sc_services_item_number\">06.<\/span><\/div><div class=\"sc_services_item_content_inner_bottom\">\n                <h6 class=\"sc_services_item_title\"><a href=\"https:\/\/ahmedbahaa.me\/en\/services\/transportation-system\/\">Transportation system<\/a><\/h6>\n                <div class=\"sc_services_item_text\"><p>Sed ut perspiciatis unde omnis iste natus error sit voluptatem.<\/p>\n<\/div><\/div><\/div><a class=\"sc_services_item_link\" href=\"https:\/\/ahmedbahaa.me\/en\/services\/transportation-system\/\"><\/a><\/div><\/div><\/div><div class=\"slider-slide swiper-slide\"><div data-post-id=\"68045\" class=\"sc_services_item sc_item_container post_container with_content with_image with_number post-68045 cpt_services type-cpt_services status-publish has-post-thumbnail hentry cpt_services_group-city\">\n\t\t<div class=\"sc_services_item_content\" style=\"background-image: url(https:\/\/ahmedbahaa.me\/wp-content\/uploads\/2024\/06\/service-image11-copyright-840x560.jpg);\">\n\t\t\t\t<div class=\"sc_services_item_content_inner\"><div class=\"sc_services_item_content_inner_top\"><span class=\"sc_services_item_number\">07.<\/span><\/div><div class=\"sc_services_item_content_inner_bottom\">\n                <h6 class=\"sc_services_item_title\"><a href=\"https:\/\/ahmedbahaa.me\/en\/services\/recreation-spots\/\">Recreation spots<\/a><\/h6>\n                <div class=\"sc_services_item_text\"><p>Sed ut perspiciatis unde omnis iste natus error sit voluptatem.<\/p>\n<\/div><\/div><\/div><a class=\"sc_services_item_link\" href=\"https:\/\/ahmedbahaa.me\/en\/services\/recreation-spots\/\"><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e25416e elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"e25416e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ca16018 sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"ca16018\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-975e577 sc_height_huge sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"975e577\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3d85f2c sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"3d85f2c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3cabb93 elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"3cabb93\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-339f76d sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"339f76d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a230f35 sc_height_huge sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"a230f35\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9032eae sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"9032eae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"trx_addons_has_bg_text elementor-section elementor-top-section elementor-element elementor-element-3366cae elementor-section-full_width elementor-section-height-min-height elementor-section-height-default elementor-section-items-middle sc_fly_static\" data-bg-text=\"{&quot;bg_text&quot;:&quot;$88,145\\u00a0.00 Fund Raise&quot;,&quot;bg_text_effect&quot;:&quot;none&quot;,&quot;bg_text_overlay&quot;:{&quot;url&quot;:&quot;&quot;},&quot;bg_text_left&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;bg_text_top&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;bg_text_z_index&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;bg_text_marquee&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:14,&quot;sizes&quot;:[]},&quot;bg_text_marquee_hover&quot;:&quot;&quot;,&quot;bg_text_marquee_margin&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;bg_text_reverse&quot;:0,&quot;bg_text_accelerate&quot;:1,&quot;bg_text_delimiter_icon&quot;:&quot;&quot;,&quot;bg_text_delimiter_image&quot;:&quot;https:\\\/\\\/ahmedbahaa.me\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/text-icon-3.svg&quot;,&quot;bg_text_delimiter_svg&quot;:&quot;&lt;svg width=\\&quot;111\\&quot; height=\\&quot;114\\&quot; viewBox=\\&quot;0 0 111 114\\&quot; fill=\\&quot;none\\&quot;&gt;&lt;g clip-path=\\&quot;url(#clip0_3064_660)\\&quot;&gt;&lt;path d=\\&quot;M35.3652 81.8621C35.45 79.6461 34.8341 77.8944 33.6014 76.44C32.24 74.8337 30.6793 73.4007 29.2908 71.8163C28.1744 70.5422 27.1029 69.2103 26.1641 67.8002C25.3648 66.5993 25.0245 65.2221 25.4101 63.7288C25.9081 61.8008 27.5906 61.1214 29.1414 62.3751C30.31 63.3204 31.3702 64.4132 32.4145 65.5035C36.5393 69.81 41.1591 73.5521 45.625 77.4735C49.3607 80.7534 51.6792 84.9557 52.3952 89.9236C52.7049 92.0724 52.623 94.2794 52.7019 96.4605C52.8878 101.577 53.0653 106.693 53.2414 111.81C53.2586 112.306 53.2438 112.803 53.2438 113.5C50.4287 113.124 47.6931 112.978 45.0683 112.357C41.3943 111.486 37.805 110.252 34.1739 109.195C33.3761 108.962 33.1946 108.5 33.1818 107.678C33.1478 105.567 33.168 103.42 32.7893 101.358C32.165 97.9567 30.0067 95.4011 27.6286 93.0461C24.8998 90.344 22.0753 87.7306 19.8737 84.5398C16.0512 78.9991 13.6878 72.8503 12.4225 66.2457C11.5404 61.6394 11.0177 56.9942 11.3362 52.3038C11.4812 50.1715 11.8525 48.0447 12.2677 45.9447C12.5527 44.5048 13.4624 43.7776 14.6059 43.7128C15.7366 43.6491 16.7593 44.2901 17.1547 45.6932C17.6463 47.439 17.9156 49.2515 18.2381 51.0431C18.9678 55.1 19.4244 59.2272 20.4476 63.2059C21.703 68.0861 24.9047 71.8586 28.3963 75.3243C30.6019 77.5138 32.9254 79.5819 35.3642 81.8616L35.3652 81.8621Z\\&quot; fill=\\&quot;#F6483D\\&quot;&gt;&lt;\\\/path&gt;&lt;path d=\\&quot;M75.508 81.7729C79.6825 78.2535 83.6184 74.6966 86.8171 70.3842C89.4724 66.8045 90.9384 62.7441 91.6125 58.3684C92.1504 54.8758 92.5991 51.3693 93.1504 47.8787C93.2964 46.9553 93.5927 46.0318 93.9704 45.1761C94.396 44.2123 95.2367 43.6615 96.3023 43.7172C97.324 43.7705 98.1213 44.3379 98.394 45.344C98.7712 46.7361 99.1228 48.1537 99.287 49.5837C100.235 57.8275 99.1543 65.8501 96.4847 73.6636C94.4019 79.7602 91.214 85.1858 86.6366 89.7358C85.0962 91.2674 83.5553 92.8 82.0647 94.3804C79.22 97.3968 77.7205 100.979 77.754 105.178C77.7604 105.97 77.6658 106.771 77.76 107.55C77.8748 108.499 77.5336 108.92 76.65 109.257C70.8468 111.474 64.8798 112.91 58.6787 113.303C58.4055 113.321 58.1304 113.305 57.9361 113.305C57.9361 111.318 57.8947 109.365 57.9445 107.415C58.0554 103.087 58.3108 98.7611 58.3236 94.4337C58.3389 89.3837 59.439 84.7271 62.4745 80.6273C64.2753 78.1952 66.6249 76.3443 68.8384 74.3375C72.6352 70.8952 76.3507 67.3613 80.0982 63.8638C80.4661 63.5206 80.8176 63.159 81.1835 62.8133C82.3418 61.718 83.2279 61.4979 84.2969 62.0328C85.2367 62.503 85.8211 63.7921 85.6845 65.1185C85.5015 66.8946 84.6411 68.3749 83.5114 69.659C82.0992 71.2638 80.5805 72.7755 79.0671 74.2857C76.5889 76.7587 75.7141 78.5264 75.5075 81.7729H75.508Z\\&quot; fill=\\&quot;#F6483D\\&quot;&gt;&lt;\\\/path&gt;&lt;path d=\\&quot;M55.5572 80.9013C51.1257 74.1996 46.8052 67.5282 42.3427 60.955C37.611 53.9858 31.2693 49.1514 23.1574 46.8273C22.2127 46.5569 21.2344 46.405 20.2363 46.1908C27.8389 44.0072 45.3728 46.2371 55.5404 60.9172C59.5858 55.3152 64.5847 50.9545 70.9664 48.3301C77.2997 45.7256 83.8051 44.7454 90.5979 46.1285C89.5491 46.3676 88.4831 46.5494 87.4535 46.8552C80.2089 49.0085 74.2139 53.0938 69.8076 59.264C65.8525 64.8022 62.2292 70.583 58.4768 76.2681C57.4729 77.7888 56.532 79.3513 55.5577 80.9018L55.5572 80.9013Z\\&quot; fill=\\&quot;#F6483D\\&quot;&gt;&lt;\\\/path&gt;&lt;path d=\\&quot;M82.4849 106.692C82.8433 104.621 83.1747 102.606 83.5598 100.602C83.6091 100.346 83.9069 100.1 84.1446 99.9253C93.1002 93.353 99.5149 84.8562 103.092 74.2505C105.299 67.7062 106.063 60.9621 105.573 54.0621C105.119 47.6772 103.587 41.5995 100.598 35.8337C101.98 34.6478 103.331 33.4877 104.686 32.3247C117.533 55.3621 111.081 91.0698 82.4844 106.693L82.4849 106.692Z\\&quot; fill=\\&quot;#F6483D\\&quot;&gt;&lt;\\\/path&gt;&lt;path d=\\&quot;M8.79904 28.3909C10.1403 29.4124 11.4346 30.3986 12.763 31.4108C6.36956 41.8566 4.22164 53.1317 5.81828 65.1824C7.42232 77.2873 13.083 87.2271 21.7876 95.5546C20.6821 96.8591 19.6096 98.1252 18.4287 99.5189C9.29411 91.1416 3.33802 80.9747 1.02984 68.8129C-1.94401 53.1452 1.7897 38.4706 8.79904 28.3909Z\\&quot; fill=\\&quot;#F6483D\\&quot;&gt;&lt;\\\/path&gt;&lt;path d=\\&quot;M35.831 38.9742C34.5717 37.8839 33.44 36.9445 32.3656 35.9428C32.1274 35.7207 32.014 35.2888 31.9726 34.9377C31.7847 33.3563 31.4391 31.8361 30.3695 30.4744C30.3113 31.5403 30.2532 32.6057 30.1831 33.8937C26.8207 30.3155 23.5584 26.8428 20.2956 23.3707C23.1299 28.2888 26.1975 33.0171 30.2744 36.9898C30.2507 37.0939 30.2275 37.198 30.2038 37.3021H23.5648C26.1294 38.76 28.7581 39.7343 31.695 39.3936C31.9262 39.3667 32.227 39.3836 32.4006 39.5111C33.0771 40.0077 33.7152 40.5576 34.4879 41.1857C32.2911 41.7126 30.2196 41.7948 28.1713 41.2604C22.8853 39.8812 19.2764 36.407 16.7355 31.6792C14.983 28.4193 14.2577 24.8719 14.1221 21.1995C14.0491 19.2176 14.1092 17.2308 14.1092 15.1558C20.9273 16.2391 26.8735 18.8147 31.4183 24.0296C35.0603 28.2086 36.8335 33.0674 35.831 38.9737V38.9742Z\\&quot; fill=\\&quot;#F6483D\\&quot;&gt;&lt;\\\/path&gt;&lt;path d=\\&quot;M96.4998 15.2736C96.4998 17.7421 96.6704 20.2112 96.4653 22.6478C95.9998 28.1775 93.9875 33.0627 89.9752 36.9812C86.0743 40.7905 80.7745 42.3894 75.989 41.1586C76.7208 40.5818 77.3766 40.0319 78.0714 39.5378C78.2726 39.3949 78.5955 39.3356 78.846 39.368C81.8983 39.762 84.6088 38.6966 87.5269 37.3542H80.4599C80.4146 37.2457 80.3692 37.1371 80.3238 37.0285C84.3968 32.9691 87.5403 28.2129 90.5979 23.3924C90.5368 23.3346 90.4757 23.2774 90.4145 23.2196C87.1547 26.6668 83.8948 30.1146 80.5714 33.6291C80.4668 32.5567 80.3677 31.5396 80.2474 30.3063C79.3263 31.5735 78.8894 32.858 78.8376 34.2238C78.8026 35.1373 78.5107 35.7748 77.809 36.3132C76.8411 37.0559 75.9121 37.8508 74.7361 38.8116C74.6961 37.3278 74.564 36.0483 74.6449 34.7826C74.9861 29.4461 77.5605 25.2592 81.4382 21.816C85.7094 18.0231 90.811 16.0905 96.3642 15.2333C96.4194 15.2248 96.482 15.2672 96.5003 15.2731L96.4998 15.2736Z\\&quot; fill=\\&quot;#F6483D\\&quot;&gt;&lt;\\\/path&gt;&lt;path d=\\&quot;M56.4396 25.9721C56.5219 20.1599 56.3888 14.5116 55.4539 8.91365C55.3597 8.90917 55.2655 8.90518 55.1718 8.9007C54.871 14.5729 54.5703 20.2446 54.267 25.9636C52.193 24.7343 50.7187 22.9138 49.8518 20.6062C48.3612 16.6379 48.8035 12.711 50.3055 8.86284C51.5071 5.78418 53.1797 2.98295 55.4716 0.5C57.3193 2.40816 58.6639 4.59625 59.8148 6.91533C61.0909 9.48595 61.94 12.2075 61.9612 15.0849C61.9923 19.3864 60.8799 23.2261 57.0051 25.7061C56.8794 25.7863 56.7339 25.8351 56.4406 25.9721H56.4396Z\\&quot; fill=\\&quot;#F6483D\\&quot;&gt;&lt;\\\/path&gt;&lt;path d=\\&quot;M55.4892 34.3472C60.1746 34.1376 63.2401 38.2776 63.2096 42.0272C63.1755 46.2321 59.6332 49.7361 55.3738 49.7196C51.291 49.7037 47.8487 46.1474 47.8438 41.9391C47.8383 37.7412 51.2678 34.3363 55.4897 34.3477L55.4892 34.3472Z\\&quot; fill=\\&quot;#F6483D\\&quot;&gt;&lt;\\\/path&gt;&lt;path d=\\&quot;M43.5456 31.8299C41.7818 32.1383 40.3178 31.6103 39.0155 30.4926C36.7108 28.5152 35.7054 25.8629 35.231 22.9585C34.7961 20.2958 35.1161 17.6689 35.7591 15.0724C35.8035 14.8941 35.8913 14.7272 35.9919 14.4717C41.1935 16.5811 45.2699 19.6816 46.3557 25.5994C46.7078 27.5195 46.3089 29.348 45.2305 31.0191C44.2029 29.6702 43.5328 28.2716 44.1043 26.5174C43.9208 26.7828 43.7374 27.0478 43.5002 27.391C41.9268 24.803 40.3839 22.2662 38.8415 19.73C38.7335 19.7838 38.6255 19.8375 38.5175 19.8913C40.1856 23.8516 41.8538 27.8124 43.5456 31.8289V31.8299Z\\&quot; fill=\\&quot;#F6483D\\&quot;&gt;&lt;\\\/path&gt;&lt;path d=\\&quot;M65.405 30.5992C67.4119 26.6484 69.3626 22.8087 71.3133 18.969C69.1432 20.9225 67.6782 23.4054 66.0209 25.9277C65.7591 25.34 65.548 24.8658 65.337 24.3916C65.2531 24.3891 65.1693 24.3871 65.0855 24.3846C65.0855 24.9395 64.9385 25.5487 65.1151 26.0388C65.5239 27.1739 65.0367 27.9763 64.3907 28.7812C64.26 28.9441 64.1565 29.1284 63.9908 29.3784C62.9627 27.6247 62.9302 25.8331 63.3202 24.0096C64.1595 20.0862 66.7122 17.5589 70.0934 15.7782C71.2437 15.1726 72.4942 14.7601 73.8256 14.2073C74.7718 19.1149 74.904 23.6928 71.9213 27.8045C70.6989 29.49 68.978 30.4279 66.9321 30.7014C66.4563 30.7651 65.9558 30.6421 65.405 30.6002V30.5992Z\\&quot; fill=\\&quot;#F6483D\\&quot;&gt;&lt;\\\/path&gt;&lt;path d=\\&quot;M42.6816 3.93677C43.3 5.37424 43.869 6.69715 44.475 8.10624C39.9065 9.469 35.6506 11.2686 31.6146 13.9039C30.7783 12.6428 29.9529 11.3971 29.0781 10.0782C33.2507 7.17183 37.7334 5.19842 42.6816 3.93727V3.93677Z\\&quot; fill=\\&quot;#F6483D\\&quot;&gt;&lt;\\\/path&gt;&lt;path d=\\&quot;M79.7409 8.54296C78.9372 9.90322 78.1714 11.2002 77.5299 12.2861C73.7311 10.8097 70.0373 9.37426 66.2168 7.88947C66.5255 6.68062 66.8894 5.25709 67.2853 3.70605C71.7528 4.58717 75.8943 6.15265 79.7409 8.54246V8.54296Z\\&quot; fill=\\&quot;#F6483D\\&quot;&gt;&lt;\\\/path&gt;&lt;\\\/g&gt;&lt;defs&gt;&lt;clipPath id=\\&quot;clip0_3064_660\\&quot;&gt;&lt;rect width=\\&quot;111\\&quot; height=\\&quot;113\\&quot; fill=\\&quot;white\\&quot; transform=\\&quot;translate(0 0.5)\\&quot;&gt;&lt;\\\/rect&gt;&lt;\\\/clipPath&gt;&lt;\\\/defs&gt;&lt;\\\/svg&gt;&quot;,&quot;bg_text_delimiter_rotation&quot;:0}\" data-id=\"3366cae\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1fdad9f sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"1fdad9f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7451545 elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"7451545\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-070d21f sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"070d21f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c750556 sc_height_huge sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"c750556\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-86182df elementor-section-full_width elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"86182df\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b5c5973 sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"b5c5973\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4208a89 sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"4208a89\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-14fea2b sc-tablet_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"14fea2b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-db35f7d sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"db35f7d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3e7da07 elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"3e7da07\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-fa1acf1 sc_inner_width_1_2 sc-tablet_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"fa1acf1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f9da327 sc_fly_static elementor-widget elementor-widget-trx_sc_title\" data-id=\"f9da327\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"trx_sc_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div\t\tclass=\"sc_title sc_title_default\" ><span class=\"sc_item_subtitle sc_title_subtitle sc_item_subtitle_above sc_item_title_style_default\">About Us<\/span><h1 class=\"sc_item_title sc_title_title sc_item_title_style_default sc_item_title_tag\"\n\t\t\t><span class=\"sc_item_title_text\">Driven by purpose, guided by values<\/span><\/h1><div class=\"sc_item_descr sc_title_descr\"><p>Dicta sunt explicabo. Nemo enim ipsam voluptatem quia voluptas sit aspernatur aut odit aut fugit.<\/p>\n<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9f5d4f3 sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"9f5d4f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0ee062d sc_fly_static elementor-widget elementor-widget-text-editor\" data-id=\"0ee062d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul class=\"trx_addons_list_success text_link2\">\n \t<li>Lorem ipsum dolor sit amet<\/li>\n \t<li>Adipiscing elit tempor<\/li>\n \t<li>Ut enim ad minim<\/li>\n<\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-053d7b2 sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"053d7b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-062cc41 sc_fly_static elementor-widget elementor-widget-trx_sc_button\" data-id=\"062cc41\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"trx_sc_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div\tclass=\"sc_item_button sc_button_wrap\" ><a href=\"https:\/\/ahmedbahaa.me\/en\/about-us\/\" class=\"sc_button sc_button_default sc_button_size_small sc_button_icon_left color_style_link2\" ><span class=\"sc_button_text\"><span class=\"sc_button_title\">About Us<\/span><\/span><\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-dc90ae3 sc_layouts_hide_on_mobile sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"dc90ae3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-035747f elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"035747f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-42843a1 sc_layouts_column_align_center sc_layouts_column sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"42843a1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7e9bee7 sc_height_huge sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"7e9bee7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6501ecb sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"6501ecb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-21493b6 elementor-widget__width-initial sc_fly_static elementor-widget elementor-widget-trx_sc_title\" data-id=\"21493b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"trx_sc_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div\t\tclass=\"sc_title sc_title_default\" ><span class=\"sc_item_subtitle sc_title_subtitle sc_item_subtitle_above sc_item_title_style_default\">Support our candidate<\/span><h1 class=\"sc_item_title sc_title_title sc_item_title_style_default sc_item_title_tag\"\n\t\t\t><span class=\"sc_item_title_text\">Blueprint of a modern\u2028political campaign<\/span><\/h1><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d4c13b3 elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"d4c13b3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4bd46ba sc_layouts_column_align_center sc_layouts_column sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"4bd46ba\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a741f67 sc_height_medium sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"a741f67\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d879eb4 sc_fly_static elementor-widget elementor-widget-trx_sc_services\" data-id=\"d879eb4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"trx_sc_services.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"sc_services sc_services_qw-tricolore sc_services_featured_top\"><div class=\"sc_services_columns_wrap sc_item_columns sc_item_posts_container sc_item_columns_3 trx_addons_columns_wrap columns_padding_bottom columns_in_single_row\"><div class=\"trx_addons_column-1_3 trx_addons_column-1_3-tablet trx_addons_column-1_2-mobile\"><div data-post-id=\"67965\" class=\"sc_services_item sc_item_container post_container with_content sc_services_item_featured_none post-67965 cpt_services type-cpt_services status-publish has-post-thumbnail hentry cpt_services_group-key-issues\">\n\t\t<div class=\"sc_services_item_content\">\n\t\t\t\t<div class=\"sc_services_item_content_inner\">\n\t\t\t\t\t\t<div class=\"sc_services_item_content_inner_top\">\n\t\t\t\t<div class=\"sc_services_item_subtitle\"><a href=\"https:\/\/ahmedbahaa.me\/en\/services_group\/key-issues\/\" title=\"View all posts in Key issues\">Key issues<\/a><\/div><div class=\"sc_services_item_decor\"><\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"sc_services_item_content_inner_bottom\">\t\t\t<h2 class=\"sc_services_item_title\"><a href=\"https:\/\/ahmedbahaa.me\/en\/services\/infrastructure-development\/\">Infrastructure development<\/a><\/h2>\n\t\t\t<div class=\"sc_services_item_info_wrap\"><div class=\"sc_services_item_text\"><p>Sed ut perspiciatis unde omnis iste natus ut perspic iatis unde omnis.<\/p>\n<\/div><\/div><\/div><\/div><a class=\"sc_services_item_link\" href=\"https:\/\/ahmedbahaa.me\/en\/services\/infrastructure-development\/\"><\/a><\/div><\/div><\/div><div class=\"trx_addons_column-1_3 trx_addons_column-1_3-tablet trx_addons_column-1_2-mobile\"><div data-post-id=\"67964\" class=\"sc_services_item sc_item_container post_container with_content sc_services_item_featured_none post-67964 cpt_services type-cpt_services status-publish has-post-thumbnail hentry cpt_services_group-key-issues\">\n\t\t<div class=\"sc_services_item_content\">\n\t\t\t\t<div class=\"sc_services_item_content_inner\">\n\t\t\t\t\t\t<div class=\"sc_services_item_content_inner_top\">\n\t\t\t\t<div class=\"sc_services_item_subtitle\"><a href=\"https:\/\/ahmedbahaa.me\/en\/services_group\/key-issues\/\" title=\"View all posts in Key issues\">Key issues<\/a><\/div><div class=\"sc_services_item_decor\"><\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"sc_services_item_content_inner_bottom\">\t\t\t<h2 class=\"sc_services_item_title\"><a href=\"https:\/\/ahmedbahaa.me\/en\/services\/international-relations\/\">International relations<\/a><\/h2>\n\t\t\t<div class=\"sc_services_item_info_wrap\"><div class=\"sc_services_item_text\"><p>Sed ut perspiciatis unde omnis iste natus ut perspic iatis unde omnis.<\/p>\n<\/div><\/div><\/div><\/div><a class=\"sc_services_item_link\" href=\"https:\/\/ahmedbahaa.me\/en\/services\/international-relations\/\"><\/a><\/div><\/div><\/div><div class=\"trx_addons_column-1_3 trx_addons_column-1_3-tablet trx_addons_column-1_2-mobile\"><div data-post-id=\"67963\" class=\"sc_services_item sc_item_container post_container with_content sc_services_item_featured_none post-67963 cpt_services type-cpt_services status-publish has-post-thumbnail hentry cpt_services_group-key-issues\">\n\t\t<div class=\"sc_services_item_content\">\n\t\t\t\t<div class=\"sc_services_item_content_inner\">\n\t\t\t\t\t\t<div class=\"sc_services_item_content_inner_top\">\n\t\t\t\t<div class=\"sc_services_item_subtitle\"><a href=\"https:\/\/ahmedbahaa.me\/en\/services_group\/key-issues\/\" title=\"View all posts in Key issues\">Key issues<\/a><\/div><div class=\"sc_services_item_decor\"><\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"sc_services_item_content_inner_bottom\">\t\t\t<h2 class=\"sc_services_item_title\"><a href=\"https:\/\/ahmedbahaa.me\/en\/services\/civil-rights-and-liberties\/\">Civil rights and liberties<\/a><\/h2>\n\t\t\t<div class=\"sc_services_item_info_wrap\"><div class=\"sc_services_item_text\"><p>Sed ut perspiciatis unde omnis iste natus ut perspic iatis unde omnis.<\/p>\n<\/div><\/div><\/div><\/div><a class=\"sc_services_item_link\" href=\"https:\/\/ahmedbahaa.me\/en\/services\/civil-rights-and-liberties\/\"><\/a><\/div><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-34f5dad2 elementor-section-full_width elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"34f5dad2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7f93e88 sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"7f93e88\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6de712b8 sc_height_huge sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"6de712b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-mouse-helper=\"hover\" data-mouse-helper-hide-helper=\"0\" data-mouse-helper-centered=\"1\" data-mouse-helper-magnet=\"0\" data-mouse-helper-color=\"\" data-mouse-helper-bg-color=\"\" data-mouse-helper-bd-color=\"\" data-mouse-helper-bd-width=\"\" data-mouse-helper-mode=\"\" data-mouse-helper-axis=\"xy\" data-mouse-helper-delay=\"5\" data-mouse-helper-text=\"\" data-mouse-helper-text-size=\"\" data-mouse-helper-text-round=\"1\" data-mouse-helper-icon=\"none\" data-mouse-helper-icon-size=\"\" data-mouse-helper-icon-color=\"#FF5B4A\" data-mouse-helper-image=\"\" data-mouse-helper-layout=\"\" data-mouse-helper-class=\"\" data-mouse-helper-callback=\"\" data-mouse-helper-hide-cursor=\"0\" class=\"elementor-element elementor-element-34f03d19 sc_fly_static elementor-widget elementor-widget-trx_widget_slider\" data-id=\"34f03d19\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"trx_widget_slider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"widget_area sc_widget_slider\"><aside class=\"widget widget_slider\">\t\t\t<div class=\"slider_wrap slider_engine_swiper\">\n\t\t\t\t<div class=\"slider_outer slider_swiper_outer slider_style_default slider_source_custom slider_outer_direction_horizontal slider_outer_multi slider_outer_nopagination slider_outer_nocontrols slider_outer_nocentered slider_outer_overflow_hidden slider_outer_notitles slider_outer_height_auto\"><div class=\"slider_container slider_swiper swiper-slider-container slider_direction_horizontal slider_nopagination slider_multi slider_type_images slider_nocontrols slider_nocentered slider_overflow_hidden slider_notitles slider_noresize slider_noswipe slider_height_auto\" data-ratio=\"16:9\" data-interval=\"0\" data-speed=\"4000\" data-effect=\"slide\" data-pagination=\"bullets\" data-direction=\"horizontal\" data-slides-per-view=\"8\" data-slides-space=\"0\" data-slides-parallax=\"0\" data-slides-centered=\"0\" data-slides-overflow=\"0\" data-mouse-wheel=\"0\" data-autoplay=\"1\" data-loop=\"1\" data-free-mode=\"0\" data-slides-min-width=\"220\" data-slides-per-view-breakpoints=\"{&quot;999999&quot;:8}\" data-slides-space-breakpoints=\"{&quot;999999&quot;:&quot;0&quot;}\"><div class=\"slider-wrapper swiper-wrapper\"><div  class=\"slider-slide swiper-slide\" data-image=\"\/\/ahmedbahaa.me\/wp-content\/uploads\/2024\/12\/logo-copyright-3.png\" style=\"\"><img decoding=\"async\" src=\"\/\/ahmedbahaa.me\/wp-content\/uploads\/2024\/12\/logo-copyright-3.png\" alt=\"\"><\/div><div  class=\"slider-slide swiper-slide\" data-image=\"\/\/ahmedbahaa.me\/wp-content\/uploads\/2024\/12\/logo-copyright-4.png\" style=\"\"><img decoding=\"async\" src=\"\/\/ahmedbahaa.me\/wp-content\/uploads\/2024\/12\/logo-copyright-4.png\" alt=\"\"><\/div><div  class=\"slider-slide swiper-slide\" data-image=\"\/\/ahmedbahaa.me\/wp-content\/uploads\/2024\/12\/logo-copyright-5.png\" style=\"\"><img decoding=\"async\" src=\"\/\/ahmedbahaa.me\/wp-content\/uploads\/2024\/12\/logo-copyright-5.png\" alt=\"\"><\/div><div  class=\"slider-slide swiper-slide\" data-image=\"\/\/ahmedbahaa.me\/wp-content\/uploads\/2024\/12\/logo-copyright-1.png\" style=\"\"><img decoding=\"async\" src=\"\/\/ahmedbahaa.me\/wp-content\/uploads\/2024\/12\/logo-copyright-1.png\" alt=\"\"><\/div><div  class=\"slider-slide swiper-slide\" data-image=\"\/\/ahmedbahaa.me\/wp-content\/uploads\/2024\/12\/logo-copyright-9.png\" style=\"\"><img decoding=\"async\" src=\"\/\/ahmedbahaa.me\/wp-content\/uploads\/2024\/12\/logo-copyright-9.png\" alt=\"\"><\/div><div  class=\"slider-slide swiper-slide\" data-image=\"\/\/ahmedbahaa.me\/wp-content\/uploads\/2024\/12\/logo-copyright-8.png\" style=\"\"><img decoding=\"async\" src=\"\/\/ahmedbahaa.me\/wp-content\/uploads\/2024\/12\/logo-copyright-8.png\" alt=\"\"><\/div><div  class=\"slider-slide swiper-slide\" data-image=\"\/\/ahmedbahaa.me\/wp-content\/uploads\/2024\/12\/logo-copyright-7.png\" style=\"\"><img decoding=\"async\" src=\"\/\/ahmedbahaa.me\/wp-content\/uploads\/2024\/12\/logo-copyright-7.png\" alt=\"\"><\/div><div  class=\"slider-slide swiper-slide\" data-image=\"\/\/ahmedbahaa.me\/wp-content\/uploads\/2024\/12\/logo-copyright-6.png\" style=\"\"><img decoding=\"async\" src=\"\/\/ahmedbahaa.me\/wp-content\/uploads\/2024\/12\/logo-copyright-6.png\" alt=\"\"><\/div><div  class=\"slider-slide swiper-slide\" data-image=\"\/\/ahmedbahaa.me\/wp-content\/uploads\/2024\/12\/logo-copyright-2.png\" style=\"\"><img decoding=\"async\" src=\"\/\/ahmedbahaa.me\/wp-content\/uploads\/2024\/12\/logo-copyright-2.png\" alt=\"\"><\/div><\/div><\/div><\/div>\t\t\t<\/div>\n\t\t\t<\/aside><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1aea4d2a sc_height_huge sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"1aea4d2a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4fbc0b7 elementor-section-full_width scheme_dark elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"4fbc0b7\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b6d19b8 sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"b6d19b8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div data-parallax-params=\"{&quot;parallax&quot;:1,&quot;flow&quot;:&quot;entrance&quot;,&quot;crop&quot;:&quot;none&quot;,&quot;ease&quot;:&quot;power2&quot;,&quot;transition&quot;:1,&quot;duration&quot;:1,&quot;delay&quot;:0,&quot;squeeze&quot;:1,&quot;text&quot;:&quot;block&quot;,&quot;text_separate&quot;:0,&quot;text_wrap&quot;:0,&quot;mouse&quot;:0,&quot;mouse_type&quot;:&quot;transform3d&quot;,&quot;mouse_tilt_amount&quot;:70,&quot;mouse_speed&quot;:10,&quot;mouse_z&quot;:&quot;&quot;,&quot;mouse_handler&quot;:&quot;row&quot;,&quot;range_start&quot;:0,&quot;range_end&quot;:40,&quot;sticky_offset&quot;:0,&quot;lag&quot;:0,&quot;x_start&quot;:-1,&quot;x_start_unit&quot;:&quot;vw&quot;,&quot;x_end&quot;:0,&quot;x_end_unit&quot;:&quot;vw&quot;,&quot;y_start&quot;:0,&quot;y_start_unit&quot;:&quot;px&quot;,&quot;y_end&quot;:0,&quot;y_end_unit&quot;:&quot;px&quot;,&quot;scale_start&quot;:100,&quot;scale_end&quot;:100,&quot;rotate_start&quot;:0,&quot;rotate_end&quot;:0,&quot;opacity_start&quot;:1,&quot;opacity_end&quot;:1,&quot;crop_start&quot;:0,&quot;crop_end&quot;:100,&quot;blur_start&quot;:0,&quot;blur_end&quot;:0,&quot;backdrop_blur_start&quot;:0,&quot;backdrop_blur_end&quot;:0,&quot;range_start_tablet&quot;:0,&quot;range_end_tablet&quot;:40,&quot;sticky_offset_tablet&quot;:0,&quot;lag_tablet&quot;:0,&quot;x_start_tablet&quot;:-1,&quot;x_start_tablet_unit&quot;:&quot;vw&quot;,&quot;x_end_tablet&quot;:0,&quot;x_end_tablet_unit&quot;:&quot;vw&quot;,&quot;y_start_tablet&quot;:0,&quot;y_start_tablet_unit&quot;:&quot;px&quot;,&quot;y_end_tablet&quot;:0,&quot;y_end_tablet_unit&quot;:&quot;px&quot;,&quot;scale_start_tablet&quot;:100,&quot;scale_end_tablet&quot;:100,&quot;rotate_start_tablet&quot;:0,&quot;rotate_end_tablet&quot;:0,&quot;opacity_start_tablet&quot;:1,&quot;opacity_end_tablet&quot;:1,&quot;crop_start_tablet&quot;:0,&quot;crop_end_tablet&quot;:100,&quot;blur_start_tablet&quot;:0,&quot;blur_end_tablet&quot;:0,&quot;backdrop_blur_start_tablet&quot;:0,&quot;backdrop_blur_end_tablet&quot;:0,&quot;range_start_mobile&quot;:0,&quot;range_end_mobile&quot;:40,&quot;sticky_offset_mobile&quot;:0,&quot;lag_mobile&quot;:0,&quot;x_start_mobile&quot;:-1,&quot;x_start_mobile_unit&quot;:&quot;vw&quot;,&quot;x_end_mobile&quot;:0,&quot;x_end_mobile_unit&quot;:&quot;vw&quot;,&quot;y_start_mobile&quot;:0,&quot;y_start_mobile_unit&quot;:&quot;px&quot;,&quot;y_end_mobile&quot;:0,&quot;y_end_mobile_unit&quot;:&quot;px&quot;,&quot;scale_start_mobile&quot;:100,&quot;scale_end_mobile&quot;:100,&quot;rotate_start_mobile&quot;:0,&quot;rotate_end_mobile&quot;:0,&quot;opacity_start_mobile&quot;:1,&quot;opacity_end_mobile&quot;:1,&quot;crop_start_mobile&quot;:0,&quot;crop_end_mobile&quot;:100,&quot;blur_start_mobile&quot;:0,&quot;blur_end_mobile&quot;:0,&quot;backdrop_blur_start_mobile&quot;:0,&quot;backdrop_blur_end_mobile&quot;:0}\" class=\"elementor-element elementor-element-8acd81a elementor-widget__width-initial elementor-absolute sc_parallax sc_parallax_entrance sc_fly_static elementor-widget elementor-widget-image\" data-id=\"8acd81a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"174\" height=\"138\" src=\"https:\/\/ahmedbahaa.me\/wp-content\/uploads\/2024\/09\/ab-vector-top.svg\" class=\"attachment-full size-full wp-image-65465\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-parallax-params=\"{&quot;parallax&quot;:1,&quot;flow&quot;:&quot;entrance&quot;,&quot;crop&quot;:&quot;none&quot;,&quot;ease&quot;:&quot;power3&quot;,&quot;transition&quot;:1,&quot;duration&quot;:1,&quot;delay&quot;:0,&quot;squeeze&quot;:1,&quot;text&quot;:&quot;block&quot;,&quot;text_separate&quot;:0,&quot;text_wrap&quot;:0,&quot;mouse&quot;:0,&quot;mouse_type&quot;:&quot;transform3d&quot;,&quot;mouse_tilt_amount&quot;:70,&quot;mouse_speed&quot;:10,&quot;mouse_z&quot;:&quot;&quot;,&quot;mouse_handler&quot;:&quot;row&quot;,&quot;range_start&quot;:0,&quot;range_end&quot;:40,&quot;sticky_offset&quot;:0,&quot;lag&quot;:0,&quot;x_start&quot;:0,&quot;x_start_unit&quot;:&quot;px&quot;,&quot;x_end&quot;:0,&quot;x_end_unit&quot;:&quot;px&quot;,&quot;y_start&quot;:0,&quot;y_start_unit&quot;:&quot;px&quot;,&quot;y_end&quot;:0,&quot;y_end_unit&quot;:&quot;px&quot;,&quot;scale_start&quot;:80,&quot;scale_end&quot;:100,&quot;rotate_start&quot;:0,&quot;rotate_end&quot;:0,&quot;opacity_start&quot;:1,&quot;opacity_end&quot;:1,&quot;crop_start&quot;:0,&quot;crop_end&quot;:100,&quot;blur_start&quot;:0,&quot;blur_end&quot;:0,&quot;backdrop_blur_start&quot;:0,&quot;backdrop_blur_end&quot;:0,&quot;range_start_tablet&quot;:0,&quot;range_end_tablet&quot;:40,&quot;sticky_offset_tablet&quot;:0,&quot;lag_tablet&quot;:0,&quot;x_start_tablet&quot;:0,&quot;x_start_tablet_unit&quot;:&quot;px&quot;,&quot;x_end_tablet&quot;:0,&quot;x_end_tablet_unit&quot;:&quot;px&quot;,&quot;y_start_tablet&quot;:0,&quot;y_start_tablet_unit&quot;:&quot;px&quot;,&quot;y_end_tablet&quot;:0,&quot;y_end_tablet_unit&quot;:&quot;px&quot;,&quot;scale_start_tablet&quot;:80,&quot;scale_end_tablet&quot;:100,&quot;rotate_start_tablet&quot;:0,&quot;rotate_end_tablet&quot;:0,&quot;opacity_start_tablet&quot;:1,&quot;opacity_end_tablet&quot;:1,&quot;crop_start_tablet&quot;:0,&quot;crop_end_tablet&quot;:100,&quot;blur_start_tablet&quot;:0,&quot;blur_end_tablet&quot;:0,&quot;backdrop_blur_start_tablet&quot;:0,&quot;backdrop_blur_end_tablet&quot;:0,&quot;range_start_mobile&quot;:0,&quot;range_end_mobile&quot;:40,&quot;sticky_offset_mobile&quot;:0,&quot;lag_mobile&quot;:0,&quot;x_start_mobile&quot;:0,&quot;x_start_mobile_unit&quot;:&quot;px&quot;,&quot;x_end_mobile&quot;:0,&quot;x_end_mobile_unit&quot;:&quot;px&quot;,&quot;y_start_mobile&quot;:0,&quot;y_start_mobile_unit&quot;:&quot;px&quot;,&quot;y_end_mobile&quot;:0,&quot;y_end_mobile_unit&quot;:&quot;px&quot;,&quot;scale_start_mobile&quot;:80,&quot;scale_end_mobile&quot;:100,&quot;rotate_start_mobile&quot;:0,&quot;rotate_end_mobile&quot;:0,&quot;opacity_start_mobile&quot;:1,&quot;opacity_end_mobile&quot;:1,&quot;crop_start_mobile&quot;:0,&quot;crop_end_mobile&quot;:100,&quot;blur_start_mobile&quot;:0,&quot;blur_end_mobile&quot;:0,&quot;backdrop_blur_start_mobile&quot;:0,&quot;backdrop_blur_end_mobile&quot;:0}\" class=\"elementor-element elementor-element-3beed72 elementor-widget__width-initial elementor-absolute sc_parallax sc_parallax_entrance sc_fly_static elementor-widget elementor-widget-image\" data-id=\"3beed72\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"69\" height=\"57\" src=\"https:\/\/ahmedbahaa.me\/wp-content\/uploads\/2024\/09\/ab-vector-1.svg\" class=\"attachment-full size-full wp-image-65388\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-parallax-params=\"{&quot;parallax&quot;:1,&quot;flow&quot;:&quot;entrance&quot;,&quot;crop&quot;:&quot;none&quot;,&quot;ease&quot;:&quot;power4&quot;,&quot;transition&quot;:1,&quot;duration&quot;:1,&quot;delay&quot;:0,&quot;squeeze&quot;:1,&quot;text&quot;:&quot;block&quot;,&quot;text_separate&quot;:0,&quot;text_wrap&quot;:0,&quot;mouse&quot;:0,&quot;mouse_type&quot;:&quot;transform3d&quot;,&quot;mouse_tilt_amount&quot;:70,&quot;mouse_speed&quot;:10,&quot;mouse_z&quot;:&quot;&quot;,&quot;mouse_handler&quot;:&quot;row&quot;,&quot;range_start&quot;:0,&quot;range_end&quot;:40,&quot;sticky_offset&quot;:0,&quot;lag&quot;:0,&quot;x_start&quot;:0,&quot;x_start_unit&quot;:&quot;px&quot;,&quot;x_end&quot;:0,&quot;x_end_unit&quot;:&quot;px&quot;,&quot;y_start&quot;:0,&quot;y_start_unit&quot;:&quot;px&quot;,&quot;y_end&quot;:0,&quot;y_end_unit&quot;:&quot;px&quot;,&quot;scale_start&quot;:85,&quot;scale_end&quot;:100,&quot;rotate_start&quot;:5,&quot;rotate_end&quot;:0,&quot;opacity_start&quot;:1,&quot;opacity_end&quot;:1,&quot;crop_start&quot;:0,&quot;crop_end&quot;:100,&quot;blur_start&quot;:0,&quot;blur_end&quot;:0,&quot;backdrop_blur_start&quot;:0,&quot;backdrop_blur_end&quot;:0,&quot;range_start_tablet&quot;:0,&quot;range_end_tablet&quot;:40,&quot;sticky_offset_tablet&quot;:0,&quot;lag_tablet&quot;:0,&quot;x_start_tablet&quot;:0,&quot;x_start_tablet_unit&quot;:&quot;px&quot;,&quot;x_end_tablet&quot;:0,&quot;x_end_tablet_unit&quot;:&quot;px&quot;,&quot;y_start_tablet&quot;:0,&quot;y_start_tablet_unit&quot;:&quot;px&quot;,&quot;y_end_tablet&quot;:0,&quot;y_end_tablet_unit&quot;:&quot;px&quot;,&quot;scale_start_tablet&quot;:85,&quot;scale_end_tablet&quot;:100,&quot;rotate_start_tablet&quot;:5,&quot;rotate_end_tablet&quot;:0,&quot;opacity_start_tablet&quot;:1,&quot;opacity_end_tablet&quot;:1,&quot;crop_start_tablet&quot;:0,&quot;crop_end_tablet&quot;:100,&quot;blur_start_tablet&quot;:0,&quot;blur_end_tablet&quot;:0,&quot;backdrop_blur_start_tablet&quot;:0,&quot;backdrop_blur_end_tablet&quot;:0,&quot;range_start_mobile&quot;:0,&quot;range_end_mobile&quot;:40,&quot;sticky_offset_mobile&quot;:0,&quot;lag_mobile&quot;:0,&quot;x_start_mobile&quot;:0,&quot;x_start_mobile_unit&quot;:&quot;px&quot;,&quot;x_end_mobile&quot;:0,&quot;x_end_mobile_unit&quot;:&quot;px&quot;,&quot;y_start_mobile&quot;:0,&quot;y_start_mobile_unit&quot;:&quot;px&quot;,&quot;y_end_mobile&quot;:0,&quot;y_end_mobile_unit&quot;:&quot;px&quot;,&quot;scale_start_mobile&quot;:85,&quot;scale_end_mobile&quot;:100,&quot;rotate_start_mobile&quot;:5,&quot;rotate_end_mobile&quot;:0,&quot;opacity_start_mobile&quot;:1,&quot;opacity_end_mobile&quot;:1,&quot;crop_start_mobile&quot;:0,&quot;crop_end_mobile&quot;:100,&quot;blur_start_mobile&quot;:0,&quot;blur_end_mobile&quot;:0,&quot;backdrop_blur_start_mobile&quot;:0,&quot;backdrop_blur_end_mobile&quot;:0}\" class=\"elementor-element elementor-element-ea17761 elementor-widget__width-initial elementor-absolute sc_parallax sc_parallax_entrance sc_fly_static elementor-widget elementor-widget-image\" data-id=\"ea17761\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"50\" height=\"54\" src=\"https:\/\/ahmedbahaa.me\/wp-content\/uploads\/2024\/09\/ab-vector-3.svg\" class=\"attachment-full size-full wp-image-65387\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a570bab sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"a570bab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a530b98 elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-absolute sc_fly_static elementor-widget elementor-widget-image\" data-id=\"a530b98\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"184\" height=\"154\" src=\"https:\/\/ahmedbahaa.me\/wp-content\/uploads\/2024\/09\/ab-vector-5.svg\" class=\"attachment-full size-full wp-image-65462\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e0a1081 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"e0a1081\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-45c6340 sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"45c6340\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8fadbe5 sc_fly_static elementor-widget elementor-widget-trx_sc_title\" data-id=\"8fadbe5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"trx_sc_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div\t\tclass=\"sc_title sc_title_default\" ><h2 class=\"sc_item_title sc_title_title sc_item_title_style_default sc_item_title_tag\"\n\t\t\t><span class=\"sc_item_title_text\">Get involved in contributions to feel proud<\/span><\/h2><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b265fcf sc_layouts_column_align_right sc_layouts_column sc-mobile_layouts_column_align_left sc_layouts_column sc-tablet_layouts_column_align_left sc_layouts_column sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"b265fcf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cc05bbe sc_fly_static elementor-widget elementor-widget-trx_sc_button\" data-id=\"cc05bbe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"trx_sc_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div\tclass=\"sc_item_button sc_button_wrap\" ><a href=\"https:\/\/ahmedbahaa.me\/en\/donations\/\" class=\"sc_button sc_button_default sc_button_size_small sc_button_icon_left\" ><span class=\"sc_button_text\"><span class=\"sc_button_title\">Donate Now<\/span><\/span><\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-c1daff7 sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"c1daff7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d248d10 elementor-widget__width-initial elementor-absolute sc_fly_static elementor-widget elementor-widget-image\" data-id=\"d248d10\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"190\" height=\"178\" src=\"https:\/\/ahmedbahaa.me\/wp-content\/uploads\/2024\/09\/ab-vector-4.svg\" class=\"attachment-full size-full wp-image-65463\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-parallax-params=\"{&quot;parallax&quot;:1,&quot;flow&quot;:&quot;entrance&quot;,&quot;crop&quot;:&quot;none&quot;,&quot;ease&quot;:&quot;power1&quot;,&quot;transition&quot;:1,&quot;duration&quot;:1,&quot;delay&quot;:0,&quot;squeeze&quot;:1,&quot;text&quot;:&quot;block&quot;,&quot;text_separate&quot;:0,&quot;text_wrap&quot;:0,&quot;mouse&quot;:0,&quot;mouse_type&quot;:&quot;transform3d&quot;,&quot;mouse_tilt_amount&quot;:70,&quot;mouse_speed&quot;:10,&quot;mouse_z&quot;:&quot;&quot;,&quot;mouse_handler&quot;:&quot;row&quot;,&quot;range_start&quot;:0,&quot;range_end&quot;:40,&quot;sticky_offset&quot;:0,&quot;lag&quot;:0,&quot;x_start&quot;:0,&quot;x_start_unit&quot;:&quot;px&quot;,&quot;x_end&quot;:0,&quot;x_end_unit&quot;:&quot;px&quot;,&quot;y_start&quot;:0,&quot;y_start_unit&quot;:&quot;px&quot;,&quot;y_end&quot;:0,&quot;y_end_unit&quot;:&quot;px&quot;,&quot;scale_start&quot;:85,&quot;scale_end&quot;:100,&quot;rotate_start&quot;:-5,&quot;rotate_end&quot;:0,&quot;opacity_start&quot;:1,&quot;opacity_end&quot;:1,&quot;crop_start&quot;:0,&quot;crop_end&quot;:100,&quot;blur_start&quot;:0,&quot;blur_end&quot;:0,&quot;backdrop_blur_start&quot;:0,&quot;backdrop_blur_end&quot;:0,&quot;range_start_tablet&quot;:0,&quot;range_end_tablet&quot;:40,&quot;sticky_offset_tablet&quot;:0,&quot;lag_tablet&quot;:0,&quot;x_start_tablet&quot;:0,&quot;x_start_tablet_unit&quot;:&quot;px&quot;,&quot;x_end_tablet&quot;:0,&quot;x_end_tablet_unit&quot;:&quot;px&quot;,&quot;y_start_tablet&quot;:0,&quot;y_start_tablet_unit&quot;:&quot;px&quot;,&quot;y_end_tablet&quot;:0,&quot;y_end_tablet_unit&quot;:&quot;px&quot;,&quot;scale_start_tablet&quot;:85,&quot;scale_end_tablet&quot;:100,&quot;rotate_start_tablet&quot;:-5,&quot;rotate_end_tablet&quot;:0,&quot;opacity_start_tablet&quot;:1,&quot;opacity_end_tablet&quot;:1,&quot;crop_start_tablet&quot;:0,&quot;crop_end_tablet&quot;:100,&quot;blur_start_tablet&quot;:0,&quot;blur_end_tablet&quot;:0,&quot;backdrop_blur_start_tablet&quot;:0,&quot;backdrop_blur_end_tablet&quot;:0,&quot;range_start_mobile&quot;:0,&quot;range_end_mobile&quot;:40,&quot;sticky_offset_mobile&quot;:0,&quot;lag_mobile&quot;:0,&quot;x_start_mobile&quot;:0,&quot;x_start_mobile_unit&quot;:&quot;px&quot;,&quot;x_end_mobile&quot;:0,&quot;x_end_mobile_unit&quot;:&quot;px&quot;,&quot;y_start_mobile&quot;:0,&quot;y_start_mobile_unit&quot;:&quot;px&quot;,&quot;y_end_mobile&quot;:0,&quot;y_end_mobile_unit&quot;:&quot;px&quot;,&quot;scale_start_mobile&quot;:85,&quot;scale_end_mobile&quot;:100,&quot;rotate_start_mobile&quot;:-5,&quot;rotate_end_mobile&quot;:0,&quot;opacity_start_mobile&quot;:1,&quot;opacity_end_mobile&quot;:1,&quot;crop_start_mobile&quot;:0,&quot;crop_end_mobile&quot;:100,&quot;blur_start_mobile&quot;:0,&quot;blur_end_mobile&quot;:0,&quot;backdrop_blur_start_mobile&quot;:0,&quot;backdrop_blur_end_mobile&quot;:0}\" class=\"elementor-element elementor-element-c177a2e elementor-widget__width-initial elementor-absolute sc_parallax sc_parallax_entrance sc_fly_static elementor-widget elementor-widget-image\" data-id=\"c177a2e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"57\" height=\"63\" src=\"https:\/\/ahmedbahaa.me\/wp-content\/uploads\/2024\/09\/ab-vector-2.svg\" class=\"attachment-full size-full wp-image-65386\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-parallax-params=\"{&quot;parallax&quot;:1,&quot;flow&quot;:&quot;entrance&quot;,&quot;crop&quot;:&quot;none&quot;,&quot;ease&quot;:&quot;power2&quot;,&quot;transition&quot;:1,&quot;duration&quot;:1,&quot;delay&quot;:0,&quot;squeeze&quot;:1,&quot;text&quot;:&quot;block&quot;,&quot;text_separate&quot;:0,&quot;text_wrap&quot;:0,&quot;mouse&quot;:0,&quot;mouse_type&quot;:&quot;transform3d&quot;,&quot;mouse_tilt_amount&quot;:70,&quot;mouse_speed&quot;:10,&quot;mouse_z&quot;:&quot;&quot;,&quot;mouse_handler&quot;:&quot;row&quot;,&quot;range_start&quot;:0,&quot;range_end&quot;:40,&quot;sticky_offset&quot;:0,&quot;lag&quot;:0,&quot;x_start&quot;:1,&quot;x_start_unit&quot;:&quot;vw&quot;,&quot;x_end&quot;:0,&quot;x_end_unit&quot;:&quot;vw&quot;,&quot;y_start&quot;:0,&quot;y_start_unit&quot;:&quot;px&quot;,&quot;y_end&quot;:0,&quot;y_end_unit&quot;:&quot;px&quot;,&quot;scale_start&quot;:100,&quot;scale_end&quot;:100,&quot;rotate_start&quot;:0,&quot;rotate_end&quot;:0,&quot;opacity_start&quot;:1,&quot;opacity_end&quot;:1,&quot;crop_start&quot;:0,&quot;crop_end&quot;:100,&quot;blur_start&quot;:0,&quot;blur_end&quot;:0,&quot;backdrop_blur_start&quot;:0,&quot;backdrop_blur_end&quot;:0,&quot;range_start_tablet&quot;:0,&quot;range_end_tablet&quot;:40,&quot;sticky_offset_tablet&quot;:0,&quot;lag_tablet&quot;:0,&quot;x_start_tablet&quot;:1,&quot;x_start_tablet_unit&quot;:&quot;vw&quot;,&quot;x_end_tablet&quot;:0,&quot;x_end_tablet_unit&quot;:&quot;vw&quot;,&quot;y_start_tablet&quot;:0,&quot;y_start_tablet_unit&quot;:&quot;px&quot;,&quot;y_end_tablet&quot;:0,&quot;y_end_tablet_unit&quot;:&quot;px&quot;,&quot;scale_start_tablet&quot;:100,&quot;scale_end_tablet&quot;:100,&quot;rotate_start_tablet&quot;:0,&quot;rotate_end_tablet&quot;:0,&quot;opacity_start_tablet&quot;:1,&quot;opacity_end_tablet&quot;:1,&quot;crop_start_tablet&quot;:0,&quot;crop_end_tablet&quot;:100,&quot;blur_start_tablet&quot;:0,&quot;blur_end_tablet&quot;:0,&quot;backdrop_blur_start_tablet&quot;:0,&quot;backdrop_blur_end_tablet&quot;:0,&quot;range_start_mobile&quot;:0,&quot;range_end_mobile&quot;:40,&quot;sticky_offset_mobile&quot;:0,&quot;lag_mobile&quot;:0,&quot;x_start_mobile&quot;:1,&quot;x_start_mobile_unit&quot;:&quot;vw&quot;,&quot;x_end_mobile&quot;:0,&quot;x_end_mobile_unit&quot;:&quot;vw&quot;,&quot;y_start_mobile&quot;:0,&quot;y_start_mobile_unit&quot;:&quot;px&quot;,&quot;y_end_mobile&quot;:0,&quot;y_end_mobile_unit&quot;:&quot;px&quot;,&quot;scale_start_mobile&quot;:100,&quot;scale_end_mobile&quot;:100,&quot;rotate_start_mobile&quot;:0,&quot;rotate_end_mobile&quot;:0,&quot;opacity_start_mobile&quot;:1,&quot;opacity_end_mobile&quot;:1,&quot;crop_start_mobile&quot;:0,&quot;crop_end_mobile&quot;:100,&quot;blur_start_mobile&quot;:0,&quot;blur_end_mobile&quot;:0,&quot;backdrop_blur_start_mobile&quot;:0,&quot;backdrop_blur_end_mobile&quot;:0}\" class=\"elementor-element elementor-element-8d2ffb9 elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-absolute sc_parallax sc_parallax_entrance sc_fly_static elementor-widget elementor-widget-image\" data-id=\"8d2ffb9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"187\" height=\"149\" src=\"https:\/\/ahmedbahaa.me\/wp-content\/uploads\/2024\/09\/ab-vector-bottom.svg\" class=\"attachment-full size-full wp-image-65464\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>main issues Our priorities Sed ut perspiciatis unde omnis iste natus ut perspic iatis unde omnis iste perspiciatis ut perspiciatis unde omnis iste natus. Join Us 01. Comfort living Sed&hellip;<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-64102","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/ahmedbahaa.me\/en\/wp-json\/wp\/v2\/pages\/64102","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ahmedbahaa.me\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ahmedbahaa.me\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ahmedbahaa.me\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ahmedbahaa.me\/en\/wp-json\/wp\/v2\/comments?post=64102"}],"version-history":[{"count":0,"href":"https:\/\/ahmedbahaa.me\/en\/wp-json\/wp\/v2\/pages\/64102\/revisions"}],"wp:attachment":[{"href":"https:\/\/ahmedbahaa.me\/en\/wp-json\/wp\/v2\/media?parent=64102"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}